{"id":1858,"date":"2024-07-08T07:13:44","date_gmt":"2024-07-08T07:13:44","guid":{"rendered":"https:\/\/museodelprado-tickets.org\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/"},"modified":"2024-07-08T07:13:44","modified_gmt":"2024-07-08T07:13:44","slug":"le-musee-du-prado-pendant-la-guerre-civile","status":"publish","type":"informacion","link":"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/","title":{"rendered":"Le mus\u00e9e du Prado pendant la guerre civile"},"template":"","tags":[159],"class_list":["post-1858","informacion","type-informacion","status-publish","hentry","tag-curseur"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le mus\u00e9e du Prado pendant la guerre civile - Museo del Prado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le mus\u00e9e du Prado pendant la guerre civile - Museo del Prado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo del Prado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/informacion\\\/le-musee-du-prado-pendant-la-guerre-civile\\\/\",\"url\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/informacion\\\/le-musee-du-prado-pendant-la-guerre-civile\\\/\",\"name\":\"Le mus\u00e9e du Prado pendant la guerre civile - Museo del Prado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/#website\"},\"datePublished\":\"2024-07-08T07:13:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/informacion\\\/le-musee-du-prado-pendant-la-guerre-civile\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/informacion\\\/le-musee-du-prado-pendant-la-guerre-civile\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/informacion\\\/le-musee-du-prado-pendant-la-guerre-civile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le mus\u00e9e du Prado pendant la guerre civile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/\",\"name\":\"Museo del Prado\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/#organization\",\"name\":\"Museo del Prado\",\"url\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/museodelprado-tickets.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-image-2-e1721634394219-1.webp\",\"contentUrl\":\"https:\\\/\\\/museodelprado-tickets.org\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-image-2-e1721634394219-1.webp\",\"width\":512,\"height\":512,\"caption\":\"Museo del Prado\"},\"image\":{\"@id\":\"https:\\\/\\\/museodelprado-tickets.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le mus\u00e9e du Prado pendant la guerre civile - Museo del Prado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/","og_locale":"fr_FR","og_type":"article","og_title":"Le mus\u00e9e du Prado pendant la guerre civile - Museo del Prado","og_url":"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/","og_site_name":"Museo del Prado","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/","url":"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/","name":"Le mus\u00e9e du Prado pendant la guerre civile - Museo del Prado","isPartOf":{"@id":"https:\/\/museodelprado-tickets.org\/fr\/#website"},"datePublished":"2024-07-08T07:13:44+00:00","breadcrumb":{"@id":"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/museodelprado-tickets.org\/fr\/informacion\/le-musee-du-prado-pendant-la-guerre-civile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/museodelprado-tickets.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Le mus\u00e9e du Prado pendant la guerre civile"}]},{"@type":"WebSite","@id":"https:\/\/museodelprado-tickets.org\/fr\/#website","url":"https:\/\/museodelprado-tickets.org\/fr\/","name":"Museo del Prado","description":"","publisher":{"@id":"https:\/\/museodelprado-tickets.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museodelprado-tickets.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/museodelprado-tickets.org\/fr\/#organization","name":"Museo del Prado","url":"https:\/\/museodelprado-tickets.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/museodelprado-tickets.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/museodelprado-tickets.org\/wp-content\/uploads\/2024\/07\/cropped-image-2-e1721634394219-1.webp","contentUrl":"https:\/\/museodelprado-tickets.org\/wp-content\/uploads\/2024\/07\/cropped-image-2-e1721634394219-1.webp","width":512,"height":512,"caption":"Museo del Prado"},"image":{"@id":"https:\/\/museodelprado-tickets.org\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/museodelprado-tickets.org\/fr\/wp-json\/wp\/v2\/informacion\/1858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museodelprado-tickets.org\/fr\/wp-json\/wp\/v2\/informacion"}],"about":[{"href":"https:\/\/museodelprado-tickets.org\/fr\/wp-json\/wp\/v2\/types\/informacion"}],"wp:attachment":[{"href":"https:\/\/museodelprado-tickets.org\/fr\/wp-json\/wp\/v2\/media?parent=1858"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/museodelprado-tickets.org\/fr\/wp-json\/wp\/v2\/tags?post=1858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}